{"id":184,"date":"2026-02-18T23:02:50","date_gmt":"2026-02-18T22:02:50","guid":{"rendered":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/?post_type=people&#038;p=184"},"modified":"2026-02-18T23:02:50","modified_gmt":"2026-02-18T22:02:50","slug":"bas-steunenburg","status":"publish","type":"people","link":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/profielen\/bas-steunenburg\/","title":{"rendered":"Bas Steunenburg"},"content":{"rendered":"","protected":false},"featured_media":185,"template":"","subject":[],"department":[12],"class_list":["post-184","people","type-people","status-publish","has-post-thumbnail","hentry","department-waterschap"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/wp-json\/wp\/v2\/people\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/wp-json\/wp\/v2\/people"}],"about":[{"href":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/wp-json\/wp\/v2\/types\/people"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/wp-json\/wp\/v2\/media\/185"}],"wp:attachment":[{"href":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/wp-json\/wp\/v2\/media?parent=184"}],"wp:term":[{"taxonomy":"subject","embeddable":true,"href":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/wp-json\/wp\/v2\/subject?post=184"},{"taxonomy":"department","embeddable":true,"href":"https:\/\/www.vvd.nl\/gemeente-sint-michielsgestel\/wp-json\/wp\/v2\/department?post=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}